{"id":10048,"date":"2026-01-30T19:00:00","date_gmt":"2026-01-30T19:00:00","guid":{"rendered":"https:\/\/radiomanchetefm.com.br\/wp\/2026\/01\/30\/resultado-da-lotofacil-3601-de-sexta-feira-30-01-2026\/"},"modified":"2026-01-30T19:00:00","modified_gmt":"2026-01-30T19:00:00","slug":"resultado-da-lotofacil-3601-de-sexta-feira-30-01-2026","status":"publish","type":"post","link":"https:\/\/radiomanchetefm.com.br\/wp\/2026\/01\/30\/resultado-da-lotofacil-3601-de-sexta-feira-30-01-2026\/","title":{"rendered":"Resultado da lotof\u00e1cil 3601 de sexta-feira (30\/01\/2026)"},"content":{"rendered":"<p>O sorteio da <strong>Lotof\u00e1cil concurso 3601<\/strong>\u00a0acontece nesta <strong>sexta-feira, 30 de janeiro de 2026, a partir das 21h (hor\u00e1rio de Bras\u00edlia)<\/strong>. Realizado pela <strong>Caixa Econ\u00f4mica Federal<\/strong>, o evento ser\u00e1 <a href=\"https:\/\/www.youtube.com\/@canalcaixa\/streams\" target=\"_blank\" rel=\"noopener\">transmitido ao vivo pelas redes oficiais<\/a>. Acompanhe aqui a cobertura completa e confira os n\u00fameros assim que forem divulgados oficialmente.<\/p>\n<h2>N\u00fameros sorteados Lotof\u00e1cil 3601<\/h2>\n<p><strong>02 &#8211; 03 &#8211; 04 &#8211; 06 &#8211; 07 &#8211; 08 &#8211; 09 &#8211; 11 &#8211; 16 &#8211; 17 &#8211; 20 &#8211; 21 &#8211;\u00a0 23 &#8211; 24 &#8211; 25\u00a0<\/strong><\/p>\n<\/p>\n<h2>Qual o valor das apostas da LotoF\u00e1cil?<\/h2>\n<p>A aposta m\u00ednima, de 15 n\u00fameros, custa R$ 3,50 com chance de 1 em 3.268.760 e a m\u00e1xima custa R$ 46.512 com chance de 1 em 211.<\/p>\n<table>\n<tbody>\n<tr>\n<th>\n<p><b>Quantidade de n\u00fameros jogados<\/b><\/p>\n<\/th>\n<th>\n<p><b>Valor da aposta<\/b><\/p>\n<\/th>\n<\/tr>\n<tr>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>15<\/p>\n<\/td>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>R$ 3,50<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>16<\/p>\n<\/td>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>R$ 48<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>17<\/p>\n<\/td>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>R$ 408<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>18<\/p>\n<\/td>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>R$ 2.448<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>19<\/p>\n<\/td>\n<td style=\"border-bottom:solid #eeeeee 1.0pt;background:white;border-top:none;border-left:none;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>R$ 11.628<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"border:none;background:white;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>20<\/p>\n<\/td>\n<td style=\"border:none;background:white;border-right:solid #eeeeee 1.0pt;padding:0cm 0cm 0cm 0cm\">\n<p>R$ 46.512<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Quando acontecem os sorteios da Lotof\u00e1cil<\/h2>\n<p>De segunda-feira a s\u00e1bado, \u00e0s 21h.<\/p>\n<h2>Facilite sua aposta na loteria com Surpresinha e Teimosinha<\/h2>\n<p>Quer apostar sem complica\u00e7\u00e3o? <strong>Use a Surpresinha<\/strong> e deixe o sistema escolher os n\u00fameros para voc\u00ea \u2014 uma forma pr\u00e1tica e r\u00e1pida de participar dos sorteios.<\/p>\n<p>Prefere insistir nos seus n\u00fameros da sorte?<strong> Aposte com a Teimosinha<\/strong> e concorra com a mesma combina\u00e7\u00e3o por por 3, 6, 12, 18 ou 24 concursos seguidos, aumentando suas chances de ganhar sem precisar refazer a aposta a cada sorteio.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/brasil61.com\/api\/v1\/serve_pixel\/20291\/87460\" alt=\"Pixel Brasil 61\" class=\"b61_pixel\" width=\"0\" height=\"0\"><\/p>\n<div class=\"br61_backlink\">\n<p>\n\t\t\t\tFonte: <a href=\"https:\/\/brasil61.com\/resultado-da-lotofacil-3601-de-sexta-feira-30-01-2026-bras2615734\" title=\"Artigo Original: Resultado da lotof\u00e1cil 3601 de sexta-feira (30\/01\/2026)\" target=\"_blank\" rel=\"noopener\">Brasil 61<\/a>\n\t\t\t<\/p>\n<\/p><\/div>\n<input type=\"hidden\" id=\"baseurl\" value=\"https:\/\/radiomanchetefm.com.br\/wp\"><input type=\"hidden\" id=\"audio_nonce\" value=\"f8b7146167\"> ","protected":false},"excerpt":{"rendered":"<p>O sorteio da Lotof\u00e1cil 3601 ocorre na noite desta sexta-feira (30), no ESPA\u00c7O DA SORTE em\u00a0S\u00e3o\u00a0Paulo\u00a0(SP)<\/p>\n","protected":false},"author":2,"featured_media":10049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/posts\/10048"}],"collection":[{"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/comments?post=10048"}],"version-history":[{"count":0,"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/posts\/10048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/media\/10049"}],"wp:attachment":[{"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/media?parent=10048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/categories?post=10048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiomanchetefm.com.br\/wp\/wp-json\/wp\/v2\/tags?post=10048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}